{"id":3991,"date":"2021-02-11T12:13:35","date_gmt":"2021-02-10T15:49:51","guid":{"rendered":"https:\/\/corteospitale.org\/site\/?p=3991"},"modified":"2021-02-11T12:05:23","modified_gmt":"2021-02-11T10:05:23","slug":"danio-manfredini-tre-studi-per-una-crocifissione","status":"publish","type":"post","link":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/","title":{"rendered":"Danio Manfredini &#8211; Tre studi per una crocifissione"},"content":{"rendered":"<h1>&nbsp;Tre studi per una crocifissione<\/h1>\n<p>&nbsp;<\/p>\n<p>di e con <strong>Danio Manfredini<\/strong><br \/>\nluci <strong>Lucia Manghi<\/strong><br \/>\ncollaborazione al progetto <strong>Andrea Mazza, Luisella Del Mar, Lucia Manghi, Vincenzo Del Prete<\/strong><br \/>\ndistribuzione <strong>La Corte Ospitale<\/strong><\/p>\n<p><em>I tre studi per una crocifissione<\/em> prendono il titolo da un opera pittorica di Francis Bacon: tre dipinti accostati uno all&#8217;altro, dove sono raffigurate tre figure che evocano la condizione drammatica di soggetti appartenenti al mondo contemporaneo. Lontano dal voler riprodurre in maniera pittorica l&#8217;opera di Bacon, mi sono proposto di inventare tre soggetti teatrali che ritraggono la condizione drammatica di tre personaggi del mio tempo.<br \/>\nNel primo studio si tratta di un personaggio che vive in un contesto psichiatrico. Vaga tra poche sedie vuote, abitate dai fantasmi della sua memoria.<br \/>\nIl secondo studio \u00e8 ispirato ad un personaggio del cineasta tedesco Fassbinder. Il transessuale Elvira, colto nel bilancio della sua vita prima del gesto tragico che la conclude.<br \/>\nIl terzo studio, ispirato ad un personaggio del drammaturgo francese Kolt\u00e8s. Ritrae un extracomunitario alle prese con una grande citt\u00e0 europea: strade, parchi, barboni, polizia. Dentro, il desiderio di colmare la solitudine con un incontro e condividere una notte di pioggia.<br \/>\nI personaggi mostrano nell&#8217;evidenza del loro dolore, nell&#8217;impossibilit\u00e0 di nasconderne i segni, nella loro disperata euforia, le ferite nascoste dell&#8217;esistenza.<\/p>\n<p><em>Danio Manfredini<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Tre studi per una crocifissione &nbsp; di e con Danio Manfredini luci Lucia Manghi collaborazione al progetto Andrea Mazza, Luisella Del Mar, Lucia Manghi, Vincenzo Del Prete distribuzione La Corte Ospitale I tre studi per una crocifissione prendono il titolo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[180],"tags":[],"class_list":["post-3991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-danio-manfredini-archivio-produzioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Danio Manfredini - Tre studi per una crocifissione - LA CORTE OSPITALE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Danio Manfredini - Tre studi per una crocifissione - LA CORTE OSPITALE\" \/>\n<meta property=\"og:description\" content=\"&nbsp;Tre studi per una crocifissione &nbsp; di e con Danio Manfredini luci Lucia Manghi collaborazione al progetto Andrea Mazza, Luisella Del Mar, Lucia Manghi, Vincenzo Del Prete distribuzione La Corte Ospitale I tre studi per una crocifissione prendono il titolo &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\" \/>\n<meta property=\"og:site_name\" content=\"LA CORTE OSPITALE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/corteospitale\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-10T15:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-11T10:05:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"330\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manuela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\"},\"author\":{\"name\":\"Manuela\",\"@id\":\"https:\/\/corteospitale.org\/site\/#\/schema\/person\/2e6c7771de31d29fa1f09440dc741ce0\"},\"headline\":\"Danio Manfredini &#8211; Tre studi per una crocifissione\",\"datePublished\":\"2021-02-10T15:49:51+00:00\",\"dateModified\":\"2021-02-11T10:05:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\"},\"wordCount\":222,\"publisher\":{\"@id\":\"https:\/\/corteospitale.org\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg\",\"articleSection\":[\"Danio Manfredini\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\",\"url\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\",\"name\":\"Danio Manfredini - Tre studi per una crocifissione - LA CORTE OSPITALE\",\"isPartOf\":{\"@id\":\"https:\/\/corteospitale.org\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg\",\"datePublished\":\"2021-02-10T15:49:51+00:00\",\"dateModified\":\"2021-02-11T10:05:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage\",\"url\":\"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg\",\"contentUrl\":\"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg\",\"width\":330,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/corteospitale.org\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Danio Manfredini &#8211; Tre studi per una crocifissione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/corteospitale.org\/site\/#website\",\"url\":\"https:\/\/corteospitale.org\/site\/\",\"name\":\"LA CORTE OSPITALE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/corteospitale.org\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/corteospitale.org\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/corteospitale.org\/site\/#organization\",\"name\":\"Corte Ospitale\",\"url\":\"https:\/\/corteospitale.org\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/corteospitale.org\/site\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Corte Ospitale\"},\"image\":{\"@id\":\"https:\/\/corteospitale.org\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/corteospitale\",\"https:\/\/www.instagram.com\/corteospitale\/\",\"https:\/\/www.youtube.com\/user\/LaCorteOspitale1\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/corteospitale.org\/site\/#\/schema\/person\/2e6c7771de31d29fa1f09440dc741ce0\",\"name\":\"Manuela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/corteospitale.org\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ac6dcb2697d112cdbed0c3c486cf1a2150a160d7ea8f53aee6865d6c70612228?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ac6dcb2697d112cdbed0c3c486cf1a2150a160d7ea8f53aee6865d6c70612228?s=96&r=g\",\"caption\":\"Manuela\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Danio Manfredini - Tre studi per una crocifissione - LA CORTE OSPITALE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/","og_locale":"it_IT","og_type":"article","og_title":"Danio Manfredini - Tre studi per una crocifissione - LA CORTE OSPITALE","og_description":"&nbsp;Tre studi per una crocifissione &nbsp; di e con Danio Manfredini luci Lucia Manghi collaborazione al progetto Andrea Mazza, Luisella Del Mar, Lucia Manghi, Vincenzo Del Prete distribuzione La Corte Ospitale I tre studi per una crocifissione prendono il titolo &hellip;","og_url":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/","og_site_name":"LA CORTE OSPITALE","article_publisher":"https:\/\/www.facebook.com\/corteospitale","article_published_time":"2021-02-10T15:49:51+00:00","article_modified_time":"2021-02-11T10:05:23+00:00","og_image":[{"width":330,"height":330,"url":"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg","type":"image\/jpeg"}],"author":"Manuela","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuela","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#article","isPartOf":{"@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/"},"author":{"name":"Manuela","@id":"https:\/\/corteospitale.org\/site\/#\/schema\/person\/2e6c7771de31d29fa1f09440dc741ce0"},"headline":"Danio Manfredini &#8211; Tre studi per una crocifissione","datePublished":"2021-02-10T15:49:51+00:00","dateModified":"2021-02-11T10:05:23+00:00","mainEntityOfPage":{"@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/"},"wordCount":222,"publisher":{"@id":"https:\/\/corteospitale.org\/site\/#organization"},"image":{"@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage"},"thumbnailUrl":"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg","articleSection":["Danio Manfredini"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/","url":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/","name":"Danio Manfredini - Tre studi per una crocifissione - LA CORTE OSPITALE","isPartOf":{"@id":"https:\/\/corteospitale.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage"},"image":{"@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage"},"thumbnailUrl":"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg","datePublished":"2021-02-10T15:49:51+00:00","dateModified":"2021-02-11T10:05:23+00:00","breadcrumb":{"@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#primaryimage","url":"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg","contentUrl":"https:\/\/corteospitale.org\/site\/wp-content\/uploads\/2021\/02\/tre-studi-e1612972074118.jpg","width":330,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/corteospitale.org\/site\/danio-manfredini-tre-studi-per-una-crocifissione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corteospitale.org\/site\/"},{"@type":"ListItem","position":2,"name":"Danio Manfredini &#8211; Tre studi per una crocifissione"}]},{"@type":"WebSite","@id":"https:\/\/corteospitale.org\/site\/#website","url":"https:\/\/corteospitale.org\/site\/","name":"LA CORTE OSPITALE","description":"","publisher":{"@id":"https:\/\/corteospitale.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corteospitale.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/corteospitale.org\/site\/#organization","name":"Corte Ospitale","url":"https:\/\/corteospitale.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corteospitale.org\/site\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Corte Ospitale"},"image":{"@id":"https:\/\/corteospitale.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/corteospitale","https:\/\/www.instagram.com\/corteospitale\/","https:\/\/www.youtube.com\/user\/LaCorteOspitale1"]},{"@type":"Person","@id":"https:\/\/corteospitale.org\/site\/#\/schema\/person\/2e6c7771de31d29fa1f09440dc741ce0","name":"Manuela","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corteospitale.org\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ac6dcb2697d112cdbed0c3c486cf1a2150a160d7ea8f53aee6865d6c70612228?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac6dcb2697d112cdbed0c3c486cf1a2150a160d7ea8f53aee6865d6c70612228?s=96&r=g","caption":"Manuela"}}]}},"_links":{"self":[{"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/posts\/3991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/comments?post=3991"}],"version-history":[{"count":4,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/posts\/3991\/revisions"}],"predecessor-version":[{"id":4056,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/posts\/3991\/revisions\/4056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/media\/3992"}],"wp:attachment":[{"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/media?parent=3991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/categories?post=3991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corteospitale.org\/site\/wp-json\/wp\/v2\/tags?post=3991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}